{"id":7891,"date":"2021-02-01T01:12:44","date_gmt":"2021-02-01T01:12:44","guid":{"rendered":"https:\/\/www.lithuaniancitizenship.com\/ley-de-ciudadania-lituana-forma-parte-del-proceso-de-sanacion-para-litvaks\/"},"modified":"2025-09-19T12:42:10","modified_gmt":"2025-09-19T11:42:10","slug":"ley-de-ciudadania-lituana-forma-parte-del-proceso-de-sanacion-para-litvaks","status":"publish","type":"post","link":"https:\/\/www.lithuaniancitizenship.com\/es\/ley-de-ciudadania-lituana-forma-parte-del-proceso-de-sanacion-para-litvaks\/","title":{"rendered":"Ley de ciudadan\u00eda lituana forma parte del \u201cproceso de sanaci\u00f3n\u201d para Litvaks"},"content":{"rendered":"<p>Seg\u00fan abogados de inmigraci\u00f3n en Sud\u00e1frica, ha habido un reciente aumento en las solicitudes de ciudadan\u00eda lituana realizadas por Litvaks sudafricanos\u2026 Tal inter\u00e9s surgi\u00f3 luego de las enmiendas a la ley de ciudadan\u00eda. Estas quitan los obst\u00e1culos para aquellos lituanos que abandonaron el pa\u00eds entre las dos guerras mundiales y sus descendientes para as\u00ed restablecer su ciudadan\u00eda.<\/p>\n<p>Sud\u00e1frica tiene una de las di\u00e1sporas lituanas m\u00e1s grandes del mundo; El 90 por ciento de su comunidad jud\u00eda, la cual consta de de 80,000 personas, remonta su ascendencia a Lituania \u2026<\/p>\n<p>La diferencia clave que presenta la enmienda es que en vez de tener que demostrar que sus familias \u201chuyeron\u201d de Lituania entre 1919 y 1940, ahora los solicitantes deben demostrar solo que \u201cse fueron\u201d. El requisito anterior era en algunos casos una cl\u00e1usula muy dif\u00edcil de cumplir , descrito como \u201cil\u00f3gico\u201d por el ex embajador de Lituania en Israel y Sud\u00e1frica, Darius Degutis.<\/p>\n<p>Alrededor del 95 por ciento de los jud\u00edos lituanos fueron asesinados en el Holocausto. Los cr\u00edticos de la pol\u00edtica de ciudadan\u00eda previa a esta, argumentaron que aquellos que se fueron en las d\u00e9cadas previas a la Segunda Guerra Mundial hu\u00edan de un ambiente peligroso.<\/p>\n<p>Adem\u00e1s, el atractivo que supone un pasaporte de la Uni\u00f3n Europea tambi\u00e9n es un factor importante en el deseo que tienen los Litvaks de un pasaporte lituano. Debido a algunas opiniones, muchas personas no se sienten c\u00f3modas con el gobierno sudafricano, la gente quiere la seguridad de un segundo pasaporte. Est\u00e1n literalmente sacando los pasaportes de los abuelos del caj\u00f3n, ya que este es un buen momento para que se postulen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan abogados de inmigraci\u00f3n en Sud\u00e1frica, ha habido un reciente aumento en las solicitudes de ciudadan\u00eda lituana realizadas por Litvaks sudafricanos\u2026 Tal inter\u00e9s surgi\u00f3 luego de las enmiendas a la ley de ciudadan\u00eda. Estas quitan &#8230; <a title=\"Ley de ciudadan\u00eda lituana forma parte del \u201cproceso de sanaci\u00f3n\u201d para Litvaks\" class=\"read-more\" href=\"https:\/\/www.lithuaniancitizenship.com\/es\/ley-de-ciudadania-lituana-forma-parte-del-proceso-de-sanacion-para-litvaks\/\" aria-label=\"Leer m\u00e1s sobre Ley de ciudadan\u00eda lituana forma parte del \u201cproceso de sanaci\u00f3n\u201d para Litvaks\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":13993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[73,77,78,74,110,111,112],"class_list":["post-7891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-lithuania-es","tag-lithuanian-citizenship-es","tag-lithuanian-dual-citizenship-es","tag-litvak-es","tag--es","tag---es","tag----es","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/posts\/7891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/comments?post=7891"}],"version-history":[{"count":1,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/posts\/7891\/revisions"}],"predecessor-version":[{"id":67453,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/posts\/7891\/revisions\/67453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/media\/13993"}],"wp:attachment":[{"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/media?parent=7891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/categories?post=7891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lithuaniancitizenship.com\/es\/wp-json\/wp\/v2\/tags?post=7891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}